{"id":3356,"date":"2022-08-05T13:41:55","date_gmt":"2022-08-05T16:41:55","guid":{"rendered":"https:\/\/painelobesidade.com.br\/biblioteca\/nearly-a-decade-on-trends-risk-factors-and-policy-implications-in-global-obesity\/"},"modified":"2022-10-13T14:15:15","modified_gmt":"2022-10-13T17:15:15","slug":"nearly-a-decade-on-trends-risk-factors-and-policy-implications-in-global-obesity","status":"publish","type":"bibliotecacpt","link":"https:\/\/painelobesidade.com.br\/es\/biblioteca\/nearly-a-decade-on-trends-risk-factors-and-policy-implications-in-global-obesity\/","title":{"rendered":"Nearly a decade on \u0014  trends, risk factors and policy implications in global obesity"},"content":{"rendered":"","protected":false},"author":19,"featured_media":0,"template":"","tags":[245,272,273],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nearly a decade on \u0014 trends, risk factors and policy implications in global obesity<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/painelobesidade.com.br\/es\/biblioteca\/nearly-a-decade-on-trends-risk-factors-and-policy-implications-in-global-obesity\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nearly a decade on \u0014 trends, risk factors and policy implications in global obesity\" \/>\n<meta property=\"og:url\" content=\"https:\/\/painelobesidade.com.br\/es\/biblioteca\/nearly-a-decade-on-trends-risk-factors-and-policy-implications-in-global-obesity\/\" \/>\n<meta property=\"og:site_name\" content=\"Painel Brasileiro da Obesidade\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-13T17:15:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/homologacao.painelobesidade.com.br\/#organization\",\"name\":\"Painel Brasileiro da Obesidade\",\"url\":\"https:\/\/homologacao.painelobesidade.com.br\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/homologacao.painelobesidade.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/painelobesidade.com.br\/wp-content\/uploads\/2022\/12\/channels4_profile_1.png\",\"contentUrl\":\"https:\/\/painelobesidade.com.br\/wp-content\/uploads\/2022\/12\/channels4_profile_1.png\",\"width\":474,\"height\":475,\"caption\":\"Painel Brasileiro da Obesidade\"},\"image\":{\"@id\":\"https:\/\/homologacao.painelobesidade.com.br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/homologacao.painelobesidade.com.br\/#website\",\"url\":\"https:\/\/homologacao.painelobesidade.com.br\/\",\"name\":\"Painel Brasileiro da Obesidade\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/homologacao.painelobesidade.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/homologacao.painelobesidade.com.br\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/painelobesidade.com.br\/es\/biblioteca\/nearly-a-decade-on-trends-risk-factors-and-policy-implications-in-global-obesity\/\",\"url\":\"https:\/\/painelobesidade.com.br\/es\/biblioteca\/nearly-a-decade-on-trends-risk-factors-and-policy-implications-in-global-obesity\/\",\"name\":\"Nearly a decade on \\u0014 trends, risk factors and policy implications in global obesity\",\"isPartOf\":{\"@id\":\"https:\/\/homologacao.painelobesidade.com.br\/#website\"},\"datePublished\":\"2022-08-05T16:41:55+00:00\",\"dateModified\":\"2022-10-13T17:15:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/painelobesidade.com.br\/es\/biblioteca\/nearly-a-decade-on-trends-risk-factors-and-policy-implications-in-global-obesity\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/painelobesidade.com.br\/es\/biblioteca\/nearly-a-decade-on-trends-risk-factors-and-policy-implications-in-global-obesity\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/painelobesidade.com.br\/es\/biblioteca\/nearly-a-decade-on-trends-risk-factors-and-policy-implications-in-global-obesity\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Pagina inicial\",\"item\":\"https:\/\/painelobesidade.com.br\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nearly a&hellip;\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nearly a decade on \u0014 trends, risk factors and policy implications in global obesity","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/painelobesidade.com.br\/es\/biblioteca\/nearly-a-decade-on-trends-risk-factors-and-policy-implications-in-global-obesity\/","og_locale":"es_ES","og_type":"article","og_title":"Nearly a decade on \u0014 trends, risk factors and policy implications in global obesity","og_url":"https:\/\/painelobesidade.com.br\/es\/biblioteca\/nearly-a-decade-on-trends-risk-factors-and-policy-implications-in-global-obesity\/","og_site_name":"Painel Brasileiro da Obesidade","article_modified_time":"2022-10-13T17:15:15+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/homologacao.painelobesidade.com.br\/#organization","name":"Painel Brasileiro da Obesidade","url":"https:\/\/homologacao.painelobesidade.com.br\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/homologacao.painelobesidade.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/painelobesidade.com.br\/wp-content\/uploads\/2022\/12\/channels4_profile_1.png","contentUrl":"https:\/\/painelobesidade.com.br\/wp-content\/uploads\/2022\/12\/channels4_profile_1.png","width":474,"height":475,"caption":"Painel Brasileiro da Obesidade"},"image":{"@id":"https:\/\/homologacao.painelobesidade.com.br\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/homologacao.painelobesidade.com.br\/#website","url":"https:\/\/homologacao.painelobesidade.com.br\/","name":"Painel Brasileiro da Obesidade","description":"","publisher":{"@id":"https:\/\/homologacao.painelobesidade.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/homologacao.painelobesidade.com.br\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/painelobesidade.com.br\/es\/biblioteca\/nearly-a-decade-on-trends-risk-factors-and-policy-implications-in-global-obesity\/","url":"https:\/\/painelobesidade.com.br\/es\/biblioteca\/nearly-a-decade-on-trends-risk-factors-and-policy-implications-in-global-obesity\/","name":"Nearly a decade on \u0014 trends, risk factors and policy implications in global obesity","isPartOf":{"@id":"https:\/\/homologacao.painelobesidade.com.br\/#website"},"datePublished":"2022-08-05T16:41:55+00:00","dateModified":"2022-10-13T17:15:15+00:00","breadcrumb":{"@id":"https:\/\/painelobesidade.com.br\/es\/biblioteca\/nearly-a-decade-on-trends-risk-factors-and-policy-implications-in-global-obesity\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/painelobesidade.com.br\/es\/biblioteca\/nearly-a-decade-on-trends-risk-factors-and-policy-implications-in-global-obesity\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/painelobesidade.com.br\/es\/biblioteca\/nearly-a-decade-on-trends-risk-factors-and-policy-implications-in-global-obesity\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Pagina inicial","item":"https:\/\/painelobesidade.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"Nearly a&hellip;"}]}]}},"_links":{"self":[{"href":"https:\/\/painelobesidade.com.br\/es\/wp-json\/wp\/v2\/rest_biblioteca\/3356"}],"collection":[{"href":"https:\/\/painelobesidade.com.br\/es\/wp-json\/wp\/v2\/rest_biblioteca"}],"about":[{"href":"https:\/\/painelobesidade.com.br\/es\/wp-json\/wp\/v2\/types\/bibliotecacpt"}],"author":[{"embeddable":true,"href":"https:\/\/painelobesidade.com.br\/es\/wp-json\/wp\/v2\/users\/19"}],"version-history":[{"count":0,"href":"https:\/\/painelobesidade.com.br\/es\/wp-json\/wp\/v2\/rest_biblioteca\/3356\/revisions"}],"wp:attachment":[{"href":"https:\/\/painelobesidade.com.br\/es\/wp-json\/wp\/v2\/media?parent=3356"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/painelobesidade.com.br\/es\/wp-json\/wp\/v2\/tags?post=3356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}